{"id":12444,"date":"2023-12-07T11:22:29","date_gmt":"2023-12-07T10:22:29","guid":{"rendered":"https:\/\/site-test.jd-web-et-design.fr\/produit\/fontaine-pyramide-decoration-maison\/"},"modified":"2024-09-17T11:04:23","modified_gmt":"2024-09-17T09:04:23","slug":"fontaine-pyramide-decoration-maison","status":"publish","type":"product","link":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/","title":{"rendered":"Fontaine Pyramide, Ardoise naturelle H30cm"},"content":{"rendered":"<p><a href=\"https:\/\/www.facebook.com\/photo.php?fbid=10151386974500067&amp;set=a.10150417558735067.407554.40377720066&amp;type=3&amp;theater\" target=\"_blank\" rel=\"noopener\"><strong>Click here to see the presentation photo<\/strong><\/a><\/p>\n<p>\u25ba Elle fera le plus bel effet \u263c sur un meuble, une \u00e9tag\u00e8re ou une table basse<\/p>\n<p>\u25ba Ambiance d\u00e9tendue gr\u00e2ce \u00e0 l&rsquo;association naturelle de la pierre et de l&rsquo;eau<\/p>\n<p>\u25ba Decoration of entrance, office or living room<\/p>\n<p>\u25ba Thank you gift, Valentine&#039;s Day, Mother&#039;s Day<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"ILfuVd\" lang=\"fr\"><span class=\"d9FyLd\"><b>\u262f <\/b><\/span><\/span>D\u00e9coration Feng shui primordiale<\/p>\n<p>Symbole de richesse, l&rsquo;eau est un \u00e9l\u00e9ment Yang.<\/p>\n<p>L&rsquo;eau est la force la plus puissante en Feng Shui.<\/p>\n<p>\u00ab\u00a0Un lieu qui capte l&rsquo;eau est plus fort que celui qui capte le vent.\u00a0\u00bb<\/p>\n<p>L&rsquo;eau retient le Qi, le capte, elle l&rsquo;active, le cumul, en d\u00e9cuple les effets et le renforce.<\/p>\n<p>&nbsp;<\/p>\n<p>\u25ba Une fontaine avec de l&rsquo;eau mobile est \u00e0 placer uniquement dans un secteur o\u00f9 cet \u00e9l\u00e9ment est recommand\u00e9 (charte maison + \u00e9toiles volantes de l&rsquo;ann\u00e9e).<\/p>\n<p>\u25ba L&rsquo;Eau gouverne les aspects professionnelles, la carri\u00e8re, les finances et l&rsquo;ascension sociale.<\/p>\n<p>Correctement positionner succ\u00e8s et fortune assur\u00e9e, on parle ici plus de rivi\u00e8re o\u00f9 le sens et la direction de l&rsquo;\u00e9coulement est important (en fonction de la porte d&rsquo;entr\u00e9e ou fa\u00e7ade).<\/p>\n<p>Le Feng Shui compte plus d&rsquo;une dizaine de crit\u00e8res et formules afin de choisir le bon emplacement&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>Une fontaine d&rsquo;int\u00e9rieur purifie l&rsquo;air en captant les poussi\u00e8res pr\u00e9sentes dans l&rsquo;air.<\/p>\n<p>Utiliser de l&rsquo;eau distill\u00e9e, d\u00e9min\u00e9ralis\u00e9e pour limiter les algues et tartre ou changer l&rsquo;eau r\u00e9guli\u00e8rement.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Fontaine en pierre naturelle de schiste multicolore, alliant nuances de vert, d&rsquo;orange, de gris, pigment\u00e9es d&rsquo;inclusions brunes.<\/p>\n<p>Dimension : 30 x 30 x h 30 cm<\/p>\n<p>La pompe immerg\u00e9e dans le bac fait remonter l&rsquo;eau en haut de la pyramide pour que l&rsquo;eau redescende naturellement vers le bas.<\/p>\n<p>La fontaine est silencieuse car l&rsquo;eau ruisselle par \u00e9tape peu espac\u00e9e donc la chute de l&rsquo;eau est tr\u00e8s agr\u00e9able.<\/p>\n<p>Weight: 9.6 kg<\/p>\n<p>Delivered with AP500 pump<\/p>\n<p>Small decorative pebbles provided<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":12442,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[7414,7406],"product_tag":[8025,7996,8198],"class_list":["post-12444","product","type-product","status-publish","has-post-thumbnail","product_cat-deco-eau","product_cat-tous-les-produits","product_tag-fontaine","product_tag-pierre","product_tag-pyramide","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"ARQITECTURE - De la d\u00e9co, des cadeaux et de l&#039;art feng shui\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre\" \/>\n\t\t<meta property=\"og:description\" content=\"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/11\/img-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/11\/img-facebook.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2100\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1123\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-07T10:22:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-17T09:04:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/les5elements\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/11\/img-facebook.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/arqitecture.fr\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/boutique\\\/#listItem\",\"name\":\"Menu\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/boutique\\\/#listItem\",\"position\":2,\"name\":\"Menu\",\"item\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/boutique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/#listItem\",\"name\":\"Tous les produits\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/#listItem\",\"position\":3,\"name\":\"Tous les produits\",\"item\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/deco-eau\\\/#listItem\",\"name\":\"d\\u00e9co EAU\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/boutique\\\/#listItem\",\"name\":\"Menu\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/deco-eau\\\/#listItem\",\"position\":4,\"name\":\"d\\u00e9co EAU\",\"item\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/deco-eau\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#listItem\",\"name\":\"Fontaine Pyramide, Ardoise naturelle H30cm\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/#listItem\",\"name\":\"Tous les produits\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#listItem\",\"position\":5,\"name\":\"Fontaine Pyramide, Ardoise naturelle H30cm\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product-category\\\/tous-les-produits\\\/deco-eau\\\/#listItem\",\"name\":\"d\\u00e9co EAU\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#itempage\",\"url\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/\",\"name\":\"Fontaine Pyramide, Ardoise - D\\u00e9coration ambiance bien-\\u00eatre\",\"description\":\"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\\u00e9e. Silencieuse. Livr\\u00e9e avec pompe AP500 Petits galets d\\u00e9coratifs fournis.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/arqitecture.fr\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/195-thickbox_default-Fontaine-Pyramide.jpg\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#mainImage\",\"width\":600,\"height\":600,\"caption\":\"Fontaine Pyramide\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#mainImage\"},\"datePublished\":\"2023-12-07T11:22:29+01:00\",\"dateModified\":\"2024-09-17T11:04:23+02:00\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/#person\",\"name\":\"Anne-sophie Cl\\u00e9venot\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/product\\\/fontaine-pyramide-decoration-maison\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6663ce18171f99bbe1967541f90452bf3c43e13ffde0e9fb3c9f705d8111f4d6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Anne-sophie Cl\\u00e9venot\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/\",\"name\":\"Boutique en ligne Cadeaux-D\\u00e9co ARQITECTURE\",\"alternateName\":\"ARQI\",\"description\":\"De la d\\u00e9co, des cadeaux et de l'art feng shui\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/arqitecture.fr\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre","description":"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.","canonical_url":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en#listItem","position":1,"name":"Accueil","item":"https:\/\/arqitecture.fr\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/boutique\/#listItem","name":"Menu"}},{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/boutique\/#listItem","position":2,"name":"Menu","item":"https:\/\/arqitecture.fr\/en\/boutique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/#listItem","name":"Tous les produits"},"previousItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/#listItem","position":3,"name":"Tous les produits","item":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/","nextItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/deco-eau\/#listItem","name":"d\u00e9co EAU"},"previousItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/boutique\/#listItem","name":"Menu"}},{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/deco-eau\/#listItem","position":4,"name":"d\u00e9co EAU","item":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/deco-eau\/","nextItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#listItem","name":"Fontaine Pyramide, Ardoise naturelle H30cm"},"previousItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/#listItem","name":"Tous les produits"}},{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#listItem","position":5,"name":"Fontaine Pyramide, Ardoise naturelle H30cm","previousItem":{"@type":"ListItem","@id":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/deco-eau\/#listItem","name":"d\u00e9co EAU"}}]},{"@type":"ItemPage","@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#itempage","url":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/","name":"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre","description":"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/arqitecture.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/09\/195-thickbox_default-Fontaine-Pyramide.jpg","@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#mainImage","width":600,"height":600,"caption":"Fontaine Pyramide"},"primaryImageOfPage":{"@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#mainImage"},"datePublished":"2023-12-07T11:22:29+01:00","dateModified":"2024-09-17T11:04:23+02:00"},{"@type":"Person","@id":"https:\/\/arqitecture.fr\/en\/#person","name":"Anne-sophie Cl\u00e9venot","image":{"@type":"ImageObject","@id":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/6663ce18171f99bbe1967541f90452bf3c43e13ffde0e9fb3c9f705d8111f4d6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Anne-sophie Cl\u00e9venot"}},{"@type":"WebSite","@id":"https:\/\/arqitecture.fr\/en\/#website","url":"https:\/\/arqitecture.fr\/en\/","name":"Boutique en ligne Cadeaux-D\u00e9co ARQITECTURE","alternateName":"ARQI","description":"De la d\u00e9co, des cadeaux et de l'art feng shui","inLanguage":"en-GB","publisher":{"@id":"https:\/\/arqitecture.fr\/en\/#person"}}]},"og:locale":"en_GB","og:site_name":"ARQITECTURE - De la d\u00e9co, des cadeaux et de l'art feng shui","og:type":"article","og:title":"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre","og:description":"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.","og:url":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/","og:image":"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/11\/img-facebook.jpg","og:image:secure_url":"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/11\/img-facebook.jpg","og:image:width":2100,"og:image:height":1123,"article:published_time":"2023-12-07T10:22:29+00:00","article:modified_time":"2024-09-17T09:04:23+00:00","article:publisher":"https:\/\/www.facebook.com\/les5elements\/","twitter:card":"summary","twitter:title":"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre","twitter:description":"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.","twitter:image":"https:\/\/arqitecture.fr\/wp-content\/uploads\/2023\/11\/img-facebook.jpg"},"aioseo_meta_data":{"post_id":"12444","title":"Fontaine Pyramide, Ardoise - D\u00e9coration ambiance bien-\u00eatre","description":"Fontaine en pierre naturelle de schiste multicolore de la marque Cactose. Pompe immerg\u00e9e. Silencieuse. Livr\u00e9e avec pompe AP500 Petits galets d\u00e9coratifs fournis.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-07 17:38:59","updated":"2025-06-04 17:42:13","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/arqitecture.fr\/en\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/arqitecture.fr\/en\/boutique\/\" title=\"Menu\">Menu<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/\" title=\"Tous les produits\">Tous les produits<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/deco-eau\/\" title=\"d\u00e9co EAU\">d\u00e9co EAU<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFontaine Pyramide, Ardoise naturelle H30cm\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/arqitecture.fr\/en"},{"label":"Menu","link":"https:\/\/arqitecture.fr\/en\/boutique\/"},{"label":"Tous les produits","link":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/"},{"label":"d\u00e9co EAU","link":"https:\/\/arqitecture.fr\/en\/product-category\/tous-les-produits\/deco-eau\/"},{"label":"Fontaine Pyramide, Ardoise naturelle H30cm","link":"https:\/\/arqitecture.fr\/en\/product\/fontaine-pyramide-decoration-maison\/"}],"_links":{"self":[{"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/product\/12444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/media\/12442"}],"wp:attachment":[{"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/media?parent=12444"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/product_brand?post=12444"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/product_cat?post=12444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/arqitecture.fr\/en\/wp-json\/wp\/v2\/product_tag?post=12444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}